{"id":7428,"date":"2020-08-06T11:07:03","date_gmt":"2020-08-06T09:07:03","guid":{"rendered":"https:\/\/omsi.it\/wp\/?post_type=portfolio&#038;p=7428"},"modified":"2020-12-09T10:05:06","modified_gmt":"2020-12-09T09:05:06","slug":"stade-de-tennis-tanger-moroc","status":"publish","type":"portfolio","link":"https:\/\/omsi.it\/de\/portfolio\/stade-de-tennis-tanger-moroc\/","title":{"rendered":"Stade de Tennis - Tanger, Marokko"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1604921615281\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fad102849973\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fad102849973 wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >INSTALLIERTE SITZE<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-5fb2706d67cb3\" class=\"wd-rs-5fb2706d67cb3  wd-button-wrapper wd-smooth-scroll text-center\" data-smooth-time=\"200\" data-smooth-offset=\"180\"><a href=\"#m2012\" title=\"m2012\" class=\"btn btn-style-link btn-shape-rectangle btn-size-large btn-link\">M2012<\/a><\/div><div id=\"wd-5fb2707909d1b\" class=\"wd-rs-5fb2707909d1b  wd-button-wrapper wd-smooth-scroll text-center\" data-smooth-time=\"200\" data-smooth-offset=\"180\"><a href=\"#m2011\" title=\"m2011\" class=\"btn btn-style-link btn-shape-rectangle btn-size-large btn-link\">M2011<\/a><\/div><\/div><\/div><\/div><\/div><div id=\"m2012\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605261068170 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_781\" class=\"wd-images-gallery wd-wpb photoswipe-images wd-carousel-container wd-wpb\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\n\t\t\t<div class=\"wd-carousel wd-grid\"data-speed=\"5000\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"1333\" data-height=\"888\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"888\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1.jpg\" class=\"wd-gallery-image image-1\" alt=\"M2012 StadedeTennis Tanger Marokko1\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1.jpg 1333w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1-1024x682.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1-1200x799.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco1-150x100.jpg 150w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"1333\" data-height=\"888\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"888\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco.jpg\" class=\"wd-gallery-image image-2\" alt=\"M2012 StadedeTennis Tanger Marokko\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco.jpg 1333w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco-1024x682.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco-1200x799.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_StadedeTennis_Tangier_Morocco-150x100.jpg 150w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-scaled-scaled.jpg\" class=\"wd-gallery-image image-3\" alt=\"M2012 TennisStadion Marokko skaliert\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-scaled-scaled.jpg 1280w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-scaled-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-scaled-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2012_TennisStadium_Morocco-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5f687b16d0bba\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f687b16d0bba wd-title-color-primary wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >M2012<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t\n<a\n\thref=\"https:\/\/omsi.it\/de\/wpprodotto\/m2012-klappsitz-fur-sportanlagen-2\/\"\n\t\t\tclass=\"vc_single_image-wrapper\"\n\t\t\t\ttitle=\"M2012 neu montierter allgemeiner kippbarer Kunststoff-Stadionsitz\"\n\t>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2012_risermounted_general_tipup_plastic_stadium_seat-300x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"M2012 neu montierter allgemeiner kippbarer Kunststoff-Stadionsitz\" title=\"M2012 neu montierter allgemeiner kippbarer Kunststoff-Stadionsitz\" \/><\/a>\n\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div id=\"m2011\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605261114613 vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_192\" class=\"wd-images-gallery wd-wpb photoswipe-images wd-carousel-container wd-wpb\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\n\t\t\t<div class=\"wd-carousel wd-grid\"data-speed=\"5000\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-scaled-scaled.jpg\" class=\"wd-gallery-image image-1\" alt=\"M2011 TennisStadion Marokko2 skaliert\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-scaled-scaled.jpg 1280w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-scaled-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-scaled-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-scaled.jpg\" class=\"wd-gallery-image image-2\" alt=\"M2011 TennisStadion Marokko\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-scaled.jpg 1280w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-scaled-scaled.jpg\" class=\"wd-gallery-image image-3\" alt=\"M2011 TennisStadion Marokko1 skaliert\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-scaled-scaled.jpg 1280w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-scaled-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-scaled-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_TennisStadium_Morocco1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fae573150e14\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fae573150e14 wd-title-color-primary wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >M2011<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t\n<a\n\thref=\"https:\/\/omsi.it\/de\/wpprodotto\/m2011-m2011-kleiner-einteiliger-sitz-fur-sportanlagen\/\"\n\t\t\tclass=\"vc_single_image-wrapper\"\n\t\t\t\ttitle=\"M2011 Kunststoff-Stadionsitz mit hoher R\u00fcckenlehne\"\n\t>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/08\/M2011_highback_plastic_stadium_seat-300x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"M2011 Kunststoff-Stadionsitz mit hoher R\u00fcckenlehne\" title=\"M2011 Kunststoff-Stadionsitz mit hoher R\u00fcckenlehne\" \/><\/a>\n\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"SEDUTE INSTALLATE M2012M2011 M2012 M2011","protected":false},"featured_media":7430,"menu_order":50,"comment_status":"open","ping_status":"closed","template":"","project-cat":[428,175,131,126,70],"class_list":["post-7428","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-altre","project-cat-anno","project-cat-m2011","project-cat-m2012","project-cat-sport"],"_links":{"self":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/portfolio\/7428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/comments?post=7428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/media\/7430"}],"wp:attachment":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/media?parent=7428"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/project-cat?post=7428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}