{"id":7719,"date":"2020-09-17T12:21:17","date_gmt":"2020-09-17T10:21:17","guid":{"rendered":"https:\/\/omsi.it\/wp\/?post_type=product&#038;p=7719"},"modified":"2022-01-18T13:00:17","modified_gmt":"2022-01-18T12:00:17","slug":"m94-einteiliger-sitz-fur-sportanlagen","status":"publish","type":"product","link":"https:\/\/omsi.it\/de\/prodotto\/m94-seduta-monoblocco-per-impianti-sportivi\/","title":{"rendered":"M94 - Einteiliger Sitz f\u00fcr Sportanlagen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535549586274\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fbf818e303ec\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fbf818e303ec wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >TIPOLOGIE DI INSTALLAZIONE<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_column-gap-35\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5f509f6cc8ed5\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f509f6cc8ed5 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Su gradone<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t\n<a\n\thref=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_sportsfacility_PlasticSeat_withoutBackrest1.png\"\n\t\t\tclass=\"vc_single_image-wrapper  \"\n\t\tdata-lightbox=\"lightbox[rel-7719-2322482264]\"\t\ttitle=\"M94 sportsfacility PlasticSeat withoutBackrest1\"\n\t>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_sportsfacility_PlasticSeat_withoutBackrest1.png\" class=\"vc_single_image-img attachment-full\" alt=\"M94 sportsfacility PlasticSeat withoutBackrest1\" title=\"M94 sportsfacility PlasticSeat withoutBackrest1\" \/><\/a>\n\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5f22c9967081e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f22c9967081e wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Trave metallica<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t\n<a\n\thref=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_OnBeamsportsfacility_PlasticSeat.png\"\n\t\t\tclass=\"vc_single_image-wrapper  \"\n\t\tdata-lightbox=\"lightbox[rel-7719-3302185960]\"\t\ttitle=\"M94 OnBeamsportsfacility PlasticSeat\"\n\t>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_OnBeamsportsfacility_PlasticSeat.png\" class=\"vc_single_image-img attachment-full\" alt=\"M94 OnBeamsportsfacility PlasticSeat\" title=\"M94 OnBeamsportsfacility PlasticSeat\" \/><\/a>\n\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t\t<div id=\"wd-5fbf81943a802\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fbf81943a802 wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >REFERENZE<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1596099536385\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\t\t\tclass=\"wd-portfolio-element\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-projects wd-masonry wd-grid-f-col\" data-atts=\"{&quot;carousel_id&quot;:&quot;5000&quot;,&quot;speed&quot;:&quot;5000&quot;,&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;auto&quot;,&quot;slides_per_view_mobile&quot;:&quot;auto&quot;,&quot;wrap&quot;:&quot;&quot;,&quot;loop&quot;:false,&quot;autoplay&quot;:&quot;no&quot;,&quot;autoheight&quot;:&quot;no&quot;,&quot;hide_pagination_control&quot;:&quot;no&quot;,&quot;hide_pagination_control_tablet&quot;:&quot;yes&quot;,&quot;hide_pagination_control_mobile&quot;:&quot;yes&quot;,&quot;dynamic_pagination_control&quot;:&quot;no&quot;,&quot;hide_prev_next_buttons&quot;:&quot;&quot;,&quot;hide_prev_next_buttons_tablet&quot;:&quot;&quot;,&quot;hide_prev_next_buttons_mobile&quot;:&quot;&quot;,&quot;carousel_arrows_position&quot;:&quot;&quot;,&quot;hide_scrollbar&quot;:&quot;yes&quot;,&quot;hide_scrollbar_tablet&quot;:&quot;yes&quot;,&quot;hide_scrollbar_mobile&quot;:&quot;yes&quot;,&quot;scroll_per_page&quot;:&quot;yes&quot;,&quot;dragEndSpeed&quot;:200,&quot;center_mode&quot;:&quot;no&quot;,&quot;custom_sizes&quot;:&quot;&quot;,&quot;sliding_speed&quot;:false,&quot;animation&quot;:false,&quot;content_animation&quot;:false,&quot;post_type&quot;:&quot;portfolio&quot;,&quot;slider&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;,&quot;css&quot;:&quot;&quot;,&quot;effect&quot;:&quot;&quot;,&quot;spacing&quot;:&quot;0&quot;,&quot;spacing_tablet&quot;:&quot;&quot;,&quot;spacing_mobile&quot;:&quot;&quot;,&quot;carousel_sync&quot;:&quot;&quot;,&quot;sync_parent_id&quot;:&quot;&quot;,&quot;sync_child_id&quot;:&quot;&quot;,&quot;sync_group_id&quot;:&quot;group-1&quot;,&quot;scroll_carousel_init&quot;:&quot;no&quot;,&quot;disable_overflow_carousel&quot;:&quot;no&quot;,&quot;posts_per_page&quot;:&quot;2&quot;,&quot;filters&quot;:&quot;0&quot;,&quot;filters_type&quot;:&quot;masonry&quot;,&quot;include&quot;:&quot;&quot;,&quot;categories&quot;:&quot;138&quot;,&quot;style&quot;:&quot;hover&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;auto&quot;,&quot;columns_mobile&quot;:&quot;auto&quot;,&quot;pagination&quot;:&quot;pagination&quot;,&quot;ajax_page&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;order&quot;:&quot;&quot;,&quot;layout&quot;:&quot;grid&quot;,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;el_class&quot;:&quot;&quot;,&quot;el_id&quot;:&quot;&quot;,&quot;wrapper_classes&quot;:&quot;&quot;,&quot;image_size&quot;:&quot;large&quot;,&quot;image_size_custom&quot;:[],&quot;element_title&quot;:&quot;&quot;,&quot;element_title_tag&quot;:&quot;h3&quot;,&quot;inner_content&quot;:&quot;&quot;,&quot;woodmart_css_id&quot;:&quot;&quot;}\" data-source=\"shortcode\" data-paged=\"1\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t\n<article id=\"post-7735\" class=\"wd-project portfolio-entry wd-col masonry-item portfolio-hover proj-cat-altre proj-cat-anno proj-cat-m94 proj-cat-sport post-7735 portfolio type-portfolio status-publish has-post-thumbnail hentry project-cat-altre project-cat-anno project-cat-m94 project-cat-sport\">\n\t<header class=\"entry-header\">\n\t\t\t\t\t<figure class=\"entry-thumbnail color-scheme-light\">\n\t\t\t\t<a href=\"https:\/\/omsi.it\/de\/portfolio\/palaruggi-imola-italia\/\" class=\"portfolio-thumbnail\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"M94 Palaruggi Imola scaled\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-scaled-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-scaled-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-2048x1365.jpg 2048w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-scaled-scaled.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wd-portfolio-btns\">\n\t\t\t\t\t<div class=\"portfolio-enlarge wd-action-btn wd-style-icon wd-enlarge-icon\">\n\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/09\/M94_Palaruggi_Imola-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\t\t\tView Large\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"social-icons-wrapper wd-action-btn wd-style-icon wd-share-icon wd-tltp\">\n\t\t\t\t\t\t\t<a><span class=\"wd-action-icon\"><\/span><\/a>\n\t\t\t\t\t\t\t<div class=\"tooltip left\">\n\t\t\t\t\t\t\t\t<div class=\"tooltip-arrow\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"tooltip-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\" wd-social-icons  wd-style-default wd-size-small social-share wd-shape-circle color-scheme-light text-center\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/omsi.it\/de\/portfolio\/palaruggi-imola-italia\/\" target=\"_blank\" class=\" wd-social-icon social-facebook\" aria-label=\"Facebook social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/omsi.it\/de\/portfolio\/palaruggi-imola-italia\/\" target=\"_blank\" class=\" wd-social-icon social-twitter\" aria-label=\"X social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fomsi.it%2Fde%2Fportfolio%2Fpalaruggi-imola-italia%2F\" target=\"_blank\" class=\" wd-hide-md wd-social-icon social-whatsapp\" aria-label=\"WhatsApp social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"whatsapp:\/\/send?text=https%3A%2F%2Fomsi.it%2Fde%2Fportfolio%2Fpalaruggi-imola-italia%2F\" target=\"_blank\" class=\" wd-hide-lg wd-social-icon social-whatsapp\" aria-label=\"WhatsApp social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/omsi.it\/de\/portfolio\/palaruggi-imola-italia\/\" target=\"_blank\" class=\" wd-social-icon social-tg\" aria-label=\"Telegram social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"portfolio-info color-scheme-light\">\n\t\t\t\t\t\t\t<div class=\"wrap-meta\">\n\t\t\t\t\t<ul class=\"proj-cats-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Altre<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>ANNO<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>M94<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>SPORT<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"wrap-title\">\n\t\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\t<a href=\"https:\/\/omsi.it\/de\/portfolio\/palaruggi-imola-italia\/\" rel=\"bookmark\">Palaruggi \u2013 Imola, Italia<\/a>\n\t\t\t\t<\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n<\/article>\n\n<article id=\"post-7133\" class=\"wd-project portfolio-entry wd-col masonry-item portfolio-hover proj-cat-altre proj-cat-anno proj-cat-m2016 proj-cat-m94 proj-cat-sport post-7133 portfolio type-portfolio status-publish has-post-thumbnail hentry project-cat-altre project-cat-anno project-cat-m2016 project-cat-m94 project-cat-sport\">\n\t<header class=\"entry-header\">\n\t\t\t\t\t<figure class=\"entry-thumbnail color-scheme-light\">\n\t\t\t\t<a href=\"https:\/\/omsi.it\/de\/portfolio\/palaeib-brescia-italia\/\" class=\"portfolio-thumbnail\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-1024x684.jpg\" class=\"attachment-large size-large\" alt=\"M2016 sport hall Palaeib brescia basketseat 1 1 scaled\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-1024x684.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-scaled-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-scaled-1200x801.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-768x513.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-1536x1026.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-2048x1367.jpg 2048w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-scaled-scaled.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wd-portfolio-btns\">\n\t\t\t\t\t<div class=\"portfolio-enlarge wd-action-btn wd-style-icon wd-enlarge-icon\">\n\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/07\/M2016_sport_hall_Palaeib_brescia_basketseat_1-1-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\t\t\tView Large\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"social-icons-wrapper wd-action-btn wd-style-icon wd-share-icon wd-tltp\">\n\t\t\t\t\t\t\t<a><span class=\"wd-action-icon\"><\/span><\/a>\n\t\t\t\t\t\t\t<div class=\"tooltip left\">\n\t\t\t\t\t\t\t\t<div class=\"tooltip-arrow\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"tooltip-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\" wd-social-icons  wd-style-default wd-size-small social-share wd-shape-circle color-scheme-light text-center\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/omsi.it\/de\/portfolio\/palaeib-brescia-italia\/\" target=\"_blank\" class=\" wd-social-icon social-facebook\" aria-label=\"Facebook social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/omsi.it\/de\/portfolio\/palaeib-brescia-italia\/\" target=\"_blank\" class=\" wd-social-icon social-twitter\" aria-label=\"X social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fomsi.it%2Fde%2Fportfolio%2Fpalaeib-brescia-italia%2F\" target=\"_blank\" class=\" wd-hide-md wd-social-icon social-whatsapp\" aria-label=\"WhatsApp social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"whatsapp:\/\/send?text=https%3A%2F%2Fomsi.it%2Fde%2Fportfolio%2Fpalaeib-brescia-italia%2F\" target=\"_blank\" class=\" wd-hide-lg wd-social-icon social-whatsapp\" aria-label=\"WhatsApp social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/omsi.it\/de\/portfolio\/palaeib-brescia-italia\/\" target=\"_blank\" class=\" wd-social-icon social-tg\" aria-label=\"Telegram social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"portfolio-info color-scheme-light\">\n\t\t\t\t\t\t\t<div class=\"wrap-meta\">\n\t\t\t\t\t<ul class=\"proj-cats-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>Altre<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>ANNO<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>M2016<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>M94<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>SPORT<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"wrap-title\">\n\t\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\t<a href=\"https:\/\/omsi.it\/de\/portfolio\/palaeib-brescia-italia\/\" rel=\"bookmark\">Palaeib \u2013 Brescia, Italia<\/a>\n\t\t\t\t<\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n<\/article>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div id=\"contattaci\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t\t<div id=\"wd-5f228b4df145e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f228b4df145e wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >CONTATTACI PER UNA PRIMA CONSULENZA<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f608-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"608\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/product\/7719#wpcf7-f608-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"608\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f608-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Nome e Cognome (richiesto)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Email (richiesto)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Telefono<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Paese<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-300\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-300\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Area di Interesse<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-880\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-880\"><option value=\"Sport\">Sport<\/option><option value=\"Scuola\">Scuola<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Prodotto interessato<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-301\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-301\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Azienda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Indirizzo<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-576\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-576\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label>Messaggio<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-427\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-427\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto l'<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2021\/01\/Informativa-Contatti-SITO-rev2020.pdf\" target=\"_blank\" rel=\"nofollow noopener\">informativa privacy<\/a> e acconsento alla memorizzazione dei miei dati secondo quanto stabilito dal regolamento europeo per la protezione dei dati personali n. 679\/2016, GDPR.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"INVIA\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>Seduta monoblocco in polipropilene senza schienale.<\/strong><br \/>\nLa sua conformazione permette al fruitore di godersi l\u2019evento sportivo in comodit\u00e0, senza rinunciare a solidit\u00e0 e robustezza grazie ai n. 2 punti di fissaggio ed alle numerose nervature sotto-sedile.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><strong>DIMENSIONI:<\/strong><br \/>\n[table id=m94 \/]<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"btn_sara\" href=\"#contattaci\">Contattaci<\/a><\/p>\n","protected":false},"featured_media":7721,"template":"","meta":[],"product_brand":[],"product_cat":[77,79,67],"product_tag":[],"class_list":["post-7719","product","type-product","status-publish","has-post-thumbnail","product_cat-monoscocche","product_cat-senza-schienale","product_cat-sport","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/product\/7719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/media\/7721"}],"wp:attachment":[{"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/media?parent=7719"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/product_brand?post=7719"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/product_cat?post=7719"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/omsi.it\/de\/wp-json\/wp\/v2\/product_tag?post=7719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}