{"id":8693,"date":"2020-11-04T10:27:03","date_gmt":"2020-11-04T09:27:03","guid":{"rendered":"https:\/\/omsi.it\/wp\/?post_type=product&#038;p=8693"},"modified":"2025-11-11T12:40:21","modified_gmt":"2025-11-11T11:40:21","slug":"d18-seating-for-collective-spaces","status":"publish","type":"product","link":"https:\/\/omsi.it\/en\/prodotto\/d18-seduta-per-spazi-collettivi\/","title":{"rendered":"D18 - Chair for public spaces"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t\t<div id=\"wd-5fc0d2a5ab82b\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fc0d2a5ab82b wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >ALL FITTINGS<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1604483241669\"><div class=\"wpb_column vc_column_container vc_col-sm-4 text-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa278059ea42\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa278059ea42 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >4 legs<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 4LegFrame publicSpaces chair\" title=\"D18 4LegFrame publicSpaces chair\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_4LegFrame_publicSpaces_chair-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa2785419282\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa2785419282 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >With armrests<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 WithArmrests publicSpaces chairs\" title=\"D18 WithArmrests publicSpaces chairs\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_publicSpaces_chairs-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 text-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa2781cb8fe0\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa2781cb8fe0 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Upholstered<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 WithArmrests padded publicSpaces chairs\" title=\"D18 WithArmrests padded publicSpaces chairs\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_WithArmrests_padded_publicSpaces_chairs-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1602163518558\"><div class=\"wpb_column vc_column_container vc_col-sm-4 text-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa2783206a94\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa2783206a94 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >With writing tablet<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 withWritingTablet publicSpaces chair\" title=\"D18 withWritingTablet publicSpaces chair\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_withWritingTablet_publicSpaces_chair-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 text-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa27872540b3\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa27872540b3 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >5-star swivel base<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 swiwel frame publicSpaces schair\" title=\"D18 swiwel frame publicSpaces schair\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_swiwel_frame_publicSpaces_schair-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5fa2787c05c53\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5fa2787c05c53 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >On bench<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair.png\" class=\"vc_single_image-img attachment-full\" alt=\"D18 onBeam plasticChair\" title=\"D18 onBeam plasticChair\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair.png 1000w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair-600x600.png 600w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair-150x150.png 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair-300x300.png 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_onBeam_plasticChair-768x768.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t\t<div id=\"wd-5f228ce5af0f7\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f228ce5af0f7 wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >SETTINGS<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1596099963870 vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_462\" class=\"wd-images-gallery wd-wpb photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\"wd-grid-f-col wd-masonry\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:0px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-scaled-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"720\" data-height=\"1080\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-200x300.jpg\" class=\"wd-gallery-image image-1\" alt=\"D18 plasticChairs1 scaled\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-200x300.jpg 200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-scaled-150x225.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-scaled-1200x1800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-683x1024.jpg 683w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-768x1152.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-1024x1536.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-1365x2048.jpg 1365w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs1-scaled-scaled.jpg 720w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs-scaled.jpg\" class=\"wd-gallery-image image-2\" alt=\"D18 plasticChairs scaled\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs-scaled.jpg 1280w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"1280\" data-height=\"853\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-300x200.jpg\" class=\"wd-gallery-image image-3\" alt=\"D18 plasticChairs2\" srcset=\"https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-300x200.jpg 300w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-150x100.jpg 150w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-1200x800.jpg 1200w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-1024x683.jpg 1024w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-768x512.jpg 768w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-1536x1024.jpg 1536w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-2048x1365.jpg 2048w, https:\/\/omsi.it\/wp-content\/uploads\/2020\/11\/D18_plasticChairs2-scaled.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"contattaci\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t\t<div id=\"wd-5f228ced8e882\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5f228ced8e882 wd-title-color-primary wd-title-style-simple text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >CONTACT US<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f608-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"608\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/product\/8693#wpcf7-f608-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/product\/8693#wpcf7-f608-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"608\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f608-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Name and Surname (required)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Email (required)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Phone<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Country<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-300\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-300\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Area of Interest<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-880\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-880\"><option value=\"Sport\">Sport<\/option><option value=\"Scuola\">School<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Product concerned<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-301\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-301\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Company<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-6\" style='margin-bottom:20px;'>\n\t\t<p><label>Address<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-576\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-576\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><label>Message<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-427\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-427\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read the<a href=\"https:\/\/omsi.it\/wp-content\/uploads\/2021\/01\/Informativa-Contatti-SITO-rev2020.pdf\" target=\"_blank\" rel=\"nofollow noopener\">privacy disclaimer<\/a> and agree to the storage of my data as provided by the European regulations for the protection of personal data n. .679 \/ GDPR, GDPR.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"SEND\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Design semplice, confortevole, leggera e maneggevole, facile da spostare grazie al foro centrale e facile da pulire e riordinare, pu\u00f2 essere impilata fino a 22 unit\u00e0.<\/p>\n<p>La scocca prodotta con polipropilene di prima scelta \u00e8 disponibile in una vastissima gamma di colori, \u00e8 possibile applicare sul sedile un pannello imbottito con rivestimento in tessuto.<\/p>\n<p>D18 pu\u00f2 essere fornita con telaio a 4 gambe di diametro 18 mm, con o senza braccioli, con sistema di aggancio, con base girevole e con tavoletta scrittoio ideale per l\u2019utilizzo in sale conferenza.<\/p>\n<p><b>Certificata<span class=\"Apple-converted-space\">\u00a0 <\/span>EN 15373<\/b><\/p>\n<p>&nbsp;<\/p>\n[table id=d18 \/]\n<p>&nbsp;<\/p>\n<p><a class=\"btn_sara\" href=\"#contattaci\">Contattaci<\/a><\/p>\n","protected":false},"featured_media":8694,"template":"","meta":[],"product_brand":[],"product_cat":[88,68,548],"product_tag":[],"class_list":["post-8693","product","type-product","status-publish","has-post-thumbnail","product_cat-collettivita","product_cat-scuola","product_cat-sedie-2","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/product\/8693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/media\/8694"}],"wp:attachment":[{"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/media?parent=8693"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/product_brand?post=8693"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/product_cat?post=8693"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/omsi.it\/en\/wp-json\/wp\/v2\/product_tag?post=8693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}